{"id":8963,"date":"2018-11-21T12:02:27","date_gmt":"2018-11-21T10:02:27","guid":{"rendered":"https:\/\/blog.benessereviaggi.it\/?p=8963"},"modified":"2018-11-21T12:02:27","modified_gmt":"2018-11-21T10:02:27","slug":"anice-stellato-una-pianta-dalle-mille-proprieta-benefiche","status":"publish","type":"post","link":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/","title":{"rendered":"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche"},"content":{"rendered":"<h1>Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune.<\/h1>\n<p>Avete mai sentito parlare di <strong>anice stellato<\/strong>? Si tratta di un pianta molto profumata che viene utilizzata sia come<a href=\"https:\/\/blog.benessereviaggi.it\/rimedi-naturali-sconfiggere-stanchezza-acne\/7828\/\"> <strong>rimedio naturale<\/strong><\/a> per curare numerose patologie, sia un <strong>cucina<\/strong> come ingrediente aromatico.<\/p>\n<p>L\u2019anice stellato viene cos\u00ec chiamato proprio per la sua<strong> caratteristica forma di stella<\/strong>: il suo frutto infatti ha dalle 8 alle 12 punte. Di origine asiatica, una volta raccolto viene essiccato e macinato e non deve essere confuso con l\u2019anice comune. Il suo aroma \u00e8 molto intenso e in molti lo paragonano a quello della liquirizia.<\/p>\n<h2>La propriet\u00e0 benefiche<\/h2>\n<p>L\u2019anice stellato ha tantissime <strong>propriet\u00e0 benefiche<\/strong> e veniva utilizzato sin dai tempi degli Egizi e dei Romani. Essi lo utilizzavano sia come <strong>pianta aromatica<\/strong> sia come rimedio naturale per la digestione. L\u2019anice stellato infatti ha eccezionali <strong>propriet\u00e0 digestive<\/strong> ed \u00e8 un vero toccasana contro nausea, problemi intestinali e anche ansia. \u00c9 ideale inoltre contro l\u2019inappetenza e risolve problemi di <strong>gas intestinali<\/strong> contrastando aerofagia e meteorismo.<\/p>\n<p>L\u2019anice stellato ha anche <strong>propriet\u00e0<\/strong> <strong>diuretiche<\/strong> ed \u00e8 indicato per combattere la <a href=\"https:\/\/blog.benessereviaggi.it\/cellulite-e-gonfiore-provate-la-centella-asiatica\/8876\/\">ritenzione idrica<\/a>, per depurare il fegato e contrastare la pesantezza di stomaco. Con l\u2019<strong>olio essenziale<\/strong> di anice stellato si possono curare la <strong>calvizie<\/strong> e i pidocchi mentre \u00e8 un potente <strong>antinfiammatorio<\/strong> grazie all\u2019<strong>anetolo<\/strong>, un principio attivo simile a quello degli antibiotici. L\u2019anice stellato infatti \u00e8 uno \u201csciogli-muco\u201d naturale indicato per trattare bronchite, tosse, raffreddore e influenza.<\/p>\n<h2>L\u2019anice stellato in cucina<\/h2>\n<p>Questa pianta pu\u00f2 essere un valido ingrediente da inserire nelle vostre ricette. Viene generalmente utilizzato (essiccato o macinato) per aromatizzare i <strong>liquori<\/strong> come assenzio, Sambuca, Pastis e tanti altri. Grazie al suo inconfondibile sapore dolciastro l\u2019anice stellato \u00e8 utilizzati nella preparazione dei <strong>confetti,<\/strong> nel <strong>vin brul\u00e9<\/strong> e, nella cucina asiatica, per condire i ripieni e le carni di maiale e anatra.<\/p>\n<p>Da noi l\u2019anice stellato viene comunemente sfruttato per le <a href=\"https:\/\/blog.benessereviaggi.it\/pasto-abbondante-5-tisane-digestive\/7537\/\"><strong>tisane digestive<\/strong><\/a> e per aromatizzare infusi e t\u00e9. Provatelo con limone, zenzero e miele, un potente rimedio naturale contro i mali di stagione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare di anice stellato? Si tratta di un pianta molto profumata che viene utilizzata sia come rimedio naturale per curare numerose patologie, sia un cucina come ingrediente aromatico. L\u2019anice stellato viene cos\u00ec chiamato [&hellip;]<\/p>\n","protected":false},"author":76,"featured_media":8964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anice stellato: una pianta dalle mille propriet\u00e0 benefiche<\/title>\n<meta name=\"description\" content=\"Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare L&#039;anice stellato \u00e8 una pianta di origine asiatica utilizzata sia come rimedio naturale per patologie, sia in cucina come ingrediente aromatico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche\" \/>\n<meta property=\"og:description\" content=\"Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare L&#039;anice stellato \u00e8 una pianta di origine asiatica utilizzata sia come rimedio naturale per patologie, sia in cucina come ingrediente aromatico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/\" \/>\n<meta property=\"og:site_name\" content=\"BenessereViaggi Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/benessereviaggi.it\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-21T10:02:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.benessereviaggi.it\/blog\/wp-content\/uploads\/2018\/11\/star-anise-1049573_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1271\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone Di Sabatino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@viaggibenessere\" \/>\n<meta name=\"twitter:site\" content=\"@viaggibenessere\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone Di Sabatino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/\",\"url\":\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/\",\"name\":\"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche\",\"isPartOf\":{\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/#website\"},\"datePublished\":\"2018-11-21T10:02:27+00:00\",\"dateModified\":\"2018-11-21T10:02:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/#\/schema\/person\/e58e53704c1ed5162d1c6d2e344c1cba\"},\"description\":\"Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare L'anice stellato \u00e8 una pianta di origine asiatica utilizzata sia come rimedio naturale per patologie, sia in cucina come ingrediente aromatico.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.benessereviaggi.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/#website\",\"url\":\"https:\/\/www.benessereviaggi.it\/blog\/\",\"name\":\"BenessereViaggi Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.benessereviaggi.it\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/#\/schema\/person\/e58e53704c1ed5162d1c6d2e344c1cba\",\"name\":\"Simone Di Sabatino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.benessereviaggi.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/57dbb37fc9b2a0d777517b916e1c0fad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/57dbb37fc9b2a0d777517b916e1c0fad?s=96&d=mm&r=g\",\"caption\":\"Simone Di Sabatino\"},\"url\":\"https:\/\/www.benessereviaggi.it\/blog\/author\/simone-di-sabatino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche","description":"Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare L'anice stellato \u00e8 una pianta di origine asiatica utilizzata sia come rimedio naturale per patologie, sia in cucina come ingrediente aromatico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/","og_locale":"it_IT","og_type":"article","og_title":"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche","og_description":"Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare L'anice stellato \u00e8 una pianta di origine asiatica utilizzata sia come rimedio naturale per patologie, sia in cucina come ingrediente aromatico.","og_url":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/","og_site_name":"BenessereViaggi Blog","article_publisher":"https:\/\/www.facebook.com\/benessereviaggi.it","article_published_time":"2018-11-21T10:02:27+00:00","og_image":[{"width":1920,"height":1271,"url":"https:\/\/www.benessereviaggi.it\/blog\/wp-content\/uploads\/2018\/11\/star-anise-1049573_1920.jpg","type":"image\/jpeg"}],"author":"Simone Di Sabatino","twitter_card":"summary_large_image","twitter_creator":"@viaggibenessere","twitter_site":"@viaggibenessere","twitter_misc":{"Scritto da":"Simone Di Sabatino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/","url":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/","name":"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche","isPartOf":{"@id":"https:\/\/www.benessereviaggi.it\/blog\/#website"},"datePublished":"2018-11-21T10:02:27+00:00","dateModified":"2018-11-21T10:02:27+00:00","author":{"@id":"https:\/\/www.benessereviaggi.it\/blog\/#\/schema\/person\/e58e53704c1ed5162d1c6d2e344c1cba"},"description":"Utilizzato in cucina e come rimedio naturale per alcune patologie, l\u2019anice stellato non deve essere confuso con l\u2019anice comune. Avete mai sentito parlare L'anice stellato \u00e8 una pianta di origine asiatica utilizzata sia come rimedio naturale per patologie, sia in cucina come ingrediente aromatico.","breadcrumb":{"@id":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.benessereviaggi.it\/blog\/anice-stellato-una-pianta-dalle-mille-proprieta-benefiche\/8963\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.benessereviaggi.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Anice stellato: una pianta dalle mille propriet\u00e0 benefiche"}]},{"@type":"WebSite","@id":"https:\/\/www.benessereviaggi.it\/blog\/#website","url":"https:\/\/www.benessereviaggi.it\/blog\/","name":"BenessereViaggi Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.benessereviaggi.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.benessereviaggi.it\/blog\/#\/schema\/person\/e58e53704c1ed5162d1c6d2e344c1cba","name":"Simone Di Sabatino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.benessereviaggi.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/57dbb37fc9b2a0d777517b916e1c0fad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57dbb37fc9b2a0d777517b916e1c0fad?s=96&d=mm&r=g","caption":"Simone Di Sabatino"},"url":"https:\/\/www.benessereviaggi.it\/blog\/author\/simone-di-sabatino\/"}]}},"_links":{"self":[{"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/posts\/8963"}],"collection":[{"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/comments?post=8963"}],"version-history":[{"count":1,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/posts\/8963\/revisions"}],"predecessor-version":[{"id":8965,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/posts\/8963\/revisions\/8965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/media\/8964"}],"wp:attachment":[{"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/media?parent=8963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/categories?post=8963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benessereviaggi.it\/blog\/wp-json\/wp\/v2\/tags?post=8963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}